{"id":9113,"date":"2026-05-13T11:28:53","date_gmt":"2026-05-13T14:28:53","guid":{"rendered":"https:\/\/radiocruzdasarmasfm.com.br\/site\/?p=9113"},"modified":"2026-05-13T11:28:53","modified_gmt":"2026-05-13T14:28:53","slug":"quaest-lula-tem-42-das-intencoes-de-voto-no-2o-turno-flavio-41","status":"publish","type":"post","link":"https:\/\/radiocruzdasarmasfm.com.br\/site\/2026\/05\/13\/quaest-lula-tem-42-das-intencoes-de-voto-no-2o-turno-flavio-41\/","title":{"rendered":"Quaest: Lula tem 42% das inten\u00e7\u00f5es de voto no 2\u00ba turno; Fl\u00e1vio, 41%"},"content":{"rendered":"<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">A pesquisa\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Genial\/Quaest<\/strong>\u00a0divulgada nesta quarta-feira (13) mostra um empate t\u00e9cnico entre o presidente\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Luiz In\u00e1cio Lula da Silva<\/strong>\u00a0(PT), com 42% das inten\u00e7\u00f5es de voto, e o senador<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">\u00a0Fl\u00e1vio Bolsonaro<\/strong>\u00a0(PL-RJ), com 41%, em um eventual segundo turno das elei\u00e7\u00f5es presidenciais.<\/p>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">Indecisos somam 3% das inten\u00e7\u00f5es de voto, enquanto brancos, nulos e pessoas que n\u00e3o v\u00e3o votar representam 14% dos eleitores entrevistados.<\/p>\n<h2 class=\"text-2xl my-5 font-bold break-words\">Lula x Romeu Zema<\/h2>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">No segundo cen\u00e1rio, Lula acumula 44%, enquanto o ex-governador de Minas Gerais\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\"><a class=\"text-red-600 underline hover:text-red-500 font-medium break-words group-[.isActiveSource]:text-xl\" href=\"https:\/\/www.cnnbrasil.com.br\/eleicoes\/quaest-veja-como-esta-a-disputa-para-presidente-no-2o-turno-em-10-estados\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-textassist=\"true\">Romeu Zema (Novo)<\/a><\/strong>\u00a0possui 37% das inten\u00e7\u00f5es de voto.<\/p>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">Indecisos s\u00e3o 4% e brancos, nulos e pessoas que n\u00e3o v\u00e3o votar, 15%.<\/p>\n<h2 class=\"text-2xl my-5 font-bold break-words\">Lula x Ronaldo Caiado<\/h2>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">No terceiro cen\u00e1rio, Lula aparece \u00e0 frente do ex-governador de Goi\u00e1s\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Ronaldo Caiado (PSD)<\/strong>\u00a0em um eventual segundo turno das\u00a0<a class=\"text-red-600 underline hover:text-red-500 font-medium break-words group-[.isActiveSource]:text-xl\" href=\"https:\/\/www.cnnbrasil.com.br\/eleicoes\/analise-pesquisa-eleitoral-aponta-cenario-de-polarizacao-nas-eleicoes\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-textassist=\"true\">elei\u00e7\u00f5es presidenciais<\/a>. O presidente tem 44% das inten\u00e7\u00f5es de voto, contra 35% do parlamentar.<\/p>\n<h2 class=\"text-2xl my-5 font-bold break-words\">Lula x Renan Santos<\/h2>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">No \u00faltimo cen\u00e1rio testado, Lula tem 45% das inten\u00e7\u00f5es de voto, enquanto o coordenador do MBL (Movimento Brasil Livre),\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Renan Santos (Miss\u00e3o)<\/strong>, acumula 28%.<\/p>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">Indecisos somam 5% e brancos, nulos e pessoas que n\u00e3o v\u00e3o votar, 22%.<\/p>\n<h2 class=\"text-2xl my-5 font-bold break-words\">Metodologia<\/h2>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">A\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Genial\/Quaest<\/strong>\u00a0entrevistou\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">2.004 eleitores<\/strong>, entre os dias\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">8 e 11 de maio<\/strong>, por meio de\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">entrevista presencial<\/strong>. A margem de erro do levantamento \u00e9 de\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">2 pontos percentuais<\/strong>, para mais ou para menos, com intervalo de confian\u00e7a de\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">95%<\/strong>.<\/p>\n<p class=\"my-5 break-words group-[.isActiveSource]:text-xl\">A pesquisa foi contratada pelo\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">Banco Genial<\/strong>\u00a0e est\u00e1 registrada no\u00a0<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">TSE<\/strong>\u00a0(Tribunal Superior Eleitoral) sob o protocolo<strong class=\"group-[.isActiveSource]:text-xl group-[.isActiveSource]:font-bold\">\u00a0BR-03598\/2026<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesquisa\u00a0Genial\/Quaest\u00a0divulgada nesta quarta-feira (13) mostra um empate t\u00e9cnico entre o presidente\u00a0Luiz In\u00e1cio Lula da Silva\u00a0(PT), com 42% das inten\u00e7\u00f5es de voto, e o senador\u00a0Fl\u00e1vio Bolsonaro\u00a0(PL-RJ), com 41%, em um eventual segundo turno das elei\u00e7\u00f5es presidenciais. Indecisos somam 3% das inten\u00e7\u00f5es de voto, enquanto brancos, nulos e pessoas que n\u00e3o v\u00e3o votar representam 14% dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=9113"}],"version-history":[{"count":1,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9113\/revisions"}],"predecessor-version":[{"id":9115,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/posts\/9113\/revisions\/9115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/media\/9114"}],"wp:attachment":[{"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=9113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=9113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiocruzdasarmasfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=9113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}